{"id":8086,"date":"2025-06-09T09:36:15","date_gmt":"2025-06-09T07:36:15","guid":{"rendered":"https:\/\/boamusica.com\/?post_type=autores&#038;p=8086"},"modified":"2025-06-09T09:40:49","modified_gmt":"2025-06-09T07:40:49","slug":"djonga","status":"publish","type":"autores","link":"https:\/\/boamusica.com\/brasil\/autores\/djonga\/","title":{"rendered":"Djonga"},"featured_media":8080,"template":"","slider-home":[29],"class_list":["post-8086","autores","type-autores","status-publish","has-post-thumbnail","hentry","slider-home-yes"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.5 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Djonga - Boa M\u00fasica<\/title>\n<meta name=\"description\" content=\"Djonga \u00e9 um rapper e compositor de Belo Horizonte. Ele deixou sua marca na cena com suas letras sobre desigualdade social, racismo, viol\u00eancia e quest\u00f5es pol\u00edticas.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/boamusica.com\/brasil\/autores\/djonga\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Djonga - Boa M\u00fasica\" \/>\n<meta property=\"og:description\" content=\"Djonga \u00e9 um rapper e compositor de Belo Horizonte. Ele deixou sua marca na cena com suas letras sobre desigualdade social, racismo, viol\u00eancia e quest\u00f5es pol\u00edticas.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/boamusica.com\/brasil\/autores\/djonga\/\" \/>\n<meta property=\"og:site_name\" content=\"Boa M\u00fasica\" \/>\n<meta property=\"article:modified_time\" content=\"2025-06-09T07:40:49+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/boamusica.com\/wp-content\/uploads\/2025\/06\/Djonga.png\" \/>\n\t<meta property=\"og:image:width\" content=\"2560\" \/>\n\t<meta property=\"og:image:height\" content=\"1440\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/png\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data1\" content=\"1 minute\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/boamusica.com\\\/brasil\\\/autores\\\/djonga\\\/\",\"url\":\"https:\\\/\\\/boamusica.com\\\/brasil\\\/autores\\\/djonga\\\/\",\"name\":\"Djonga - Boa M\u00fasica\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/boamusica.com\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/boamusica.com\\\/brasil\\\/autores\\\/djonga\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/boamusica.com\\\/brasil\\\/autores\\\/djonga\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/boamusica.com\\\/wp-content\\\/uploads\\\/2025\\\/06\\\/Djonga.png\",\"datePublished\":\"2025-06-09T07:36:15+00:00\",\"dateModified\":\"2025-06-09T07:40:49+00:00\",\"description\":\"Djonga \u00e9 um rapper e compositor de Belo Horizonte. Ele deixou sua marca na cena com suas letras sobre desigualdade social, racismo, viol\u00eancia e quest\u00f5es pol\u00edticas.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/boamusica.com\\\/brasil\\\/autores\\\/djonga\\\/#breadcrumb\"},\"inLanguage\":\"brasil\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/boamusica.com\\\/brasil\\\/autores\\\/djonga\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"brasil\",\"@id\":\"https:\\\/\\\/boamusica.com\\\/brasil\\\/autores\\\/djonga\\\/#primaryimage\",\"url\":\"https:\\\/\\\/boamusica.com\\\/wp-content\\\/uploads\\\/2025\\\/06\\\/Djonga.png\",\"contentUrl\":\"https:\\\/\\\/boamusica.com\\\/wp-content\\\/uploads\\\/2025\\\/06\\\/Djonga.png\",\"width\":2560,\"height\":1440},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/boamusica.com\\\/brasil\\\/autores\\\/djonga\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"https:\\\/\\\/boamusica.com\\\/brasil\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Djonga\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/boamusica.com\\\/#website\",\"url\":\"https:\\\/\\\/boamusica.com\\\/\",\"name\":\"Boa M\u00fasica\",\"description\":\"Un proyecto editorial \u00e9tico y centrado en las personas. Gestionamos derechos de autor de forma integral.\",\"publisher\":{\"@id\":\"https:\\\/\\\/boamusica.com\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/boamusica.com\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"brasil\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/boamusica.com\\\/#organization\",\"name\":\"Boa M\u00fasica\",\"url\":\"https:\\\/\\\/boamusica.com\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"brasil\",\"@id\":\"https:\\\/\\\/boamusica.com\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/boamusica.com\\\/wp-content\\\/uploads\\\/2024\\\/05\\\/logo-boa-musica.webp\",\"contentUrl\":\"https:\\\/\\\/boamusica.com\\\/wp-content\\\/uploads\\\/2024\\\/05\\\/logo-boa-musica.webp\",\"width\":398,\"height\":198,\"caption\":\"Boa M\u00fasica\"},\"image\":{\"@id\":\"https:\\\/\\\/boamusica.com\\\/#\\\/schema\\\/logo\\\/image\\\/\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Djonga - Boa M\u00fasica","description":"Djonga \u00e9 um rapper e compositor de Belo Horizonte. Ele deixou sua marca na cena com suas letras sobre desigualdade social, racismo, viol\u00eancia e quest\u00f5es pol\u00edticas.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/boamusica.com\/brasil\/autores\/djonga\/","og_locale":"en_US","og_type":"article","og_title":"Djonga - Boa M\u00fasica","og_description":"Djonga \u00e9 um rapper e compositor de Belo Horizonte. Ele deixou sua marca na cena com suas letras sobre desigualdade social, racismo, viol\u00eancia e quest\u00f5es pol\u00edticas.","og_url":"https:\/\/boamusica.com\/brasil\/autores\/djonga\/","og_site_name":"Boa M\u00fasica","article_modified_time":"2025-06-09T07:40:49+00:00","og_image":[{"width":2560,"height":1440,"url":"https:\/\/boamusica.com\/wp-content\/uploads\/2025\/06\/Djonga.png","type":"image\/png"}],"twitter_card":"summary_large_image","twitter_misc":{"Est. reading time":"1 minute"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/boamusica.com\/brasil\/autores\/djonga\/","url":"https:\/\/boamusica.com\/brasil\/autores\/djonga\/","name":"Djonga - Boa M\u00fasica","isPartOf":{"@id":"https:\/\/boamusica.com\/#website"},"primaryImageOfPage":{"@id":"https:\/\/boamusica.com\/brasil\/autores\/djonga\/#primaryimage"},"image":{"@id":"https:\/\/boamusica.com\/brasil\/autores\/djonga\/#primaryimage"},"thumbnailUrl":"https:\/\/boamusica.com\/wp-content\/uploads\/2025\/06\/Djonga.png","datePublished":"2025-06-09T07:36:15+00:00","dateModified":"2025-06-09T07:40:49+00:00","description":"Djonga \u00e9 um rapper e compositor de Belo Horizonte. Ele deixou sua marca na cena com suas letras sobre desigualdade social, racismo, viol\u00eancia e quest\u00f5es pol\u00edticas.","breadcrumb":{"@id":"https:\/\/boamusica.com\/brasil\/autores\/djonga\/#breadcrumb"},"inLanguage":"brasil","potentialAction":[{"@type":"ReadAction","target":["https:\/\/boamusica.com\/brasil\/autores\/djonga\/"]}]},{"@type":"ImageObject","inLanguage":"brasil","@id":"https:\/\/boamusica.com\/brasil\/autores\/djonga\/#primaryimage","url":"https:\/\/boamusica.com\/wp-content\/uploads\/2025\/06\/Djonga.png","contentUrl":"https:\/\/boamusica.com\/wp-content\/uploads\/2025\/06\/Djonga.png","width":2560,"height":1440},{"@type":"BreadcrumbList","@id":"https:\/\/boamusica.com\/brasil\/autores\/djonga\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/boamusica.com\/brasil\/"},{"@type":"ListItem","position":2,"name":"Djonga"}]},{"@type":"WebSite","@id":"https:\/\/boamusica.com\/#website","url":"https:\/\/boamusica.com\/","name":"Boa M\u00fasica","description":"Un proyecto editorial \u00e9tico y centrado en las personas. Gestionamos derechos de autor de forma integral.","publisher":{"@id":"https:\/\/boamusica.com\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/boamusica.com\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"brasil"},{"@type":"Organization","@id":"https:\/\/boamusica.com\/#organization","name":"Boa M\u00fasica","url":"https:\/\/boamusica.com\/","logo":{"@type":"ImageObject","inLanguage":"brasil","@id":"https:\/\/boamusica.com\/#\/schema\/logo\/image\/","url":"https:\/\/boamusica.com\/wp-content\/uploads\/2024\/05\/logo-boa-musica.webp","contentUrl":"https:\/\/boamusica.com\/wp-content\/uploads\/2024\/05\/logo-boa-musica.webp","width":398,"height":198,"caption":"Boa M\u00fasica"},"image":{"@id":"https:\/\/boamusica.com\/#\/schema\/logo\/image\/"}}]}},"_links":{"self":[{"href":"https:\/\/boamusica.com\/brasil\/wp-json\/wp\/v2\/autores\/8086","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/boamusica.com\/brasil\/wp-json\/wp\/v2\/autores"}],"about":[{"href":"https:\/\/boamusica.com\/brasil\/wp-json\/wp\/v2\/types\/autores"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/boamusica.com\/brasil\/wp-json\/wp\/v2\/media\/8080"}],"wp:attachment":[{"href":"https:\/\/boamusica.com\/brasil\/wp-json\/wp\/v2\/media?parent=8086"}],"wp:term":[{"taxonomy":"slider-home","embeddable":true,"href":"https:\/\/boamusica.com\/brasil\/wp-json\/wp\/v2\/slider-home?post=8086"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}